{"id":3169,"date":"2023-09-13T10:17:51","date_gmt":"2023-09-13T08:17:51","guid":{"rendered":"http:\/\/stephankofler.com\/wordpress\/progetti\/il-vostro-progetto\/"},"modified":"2024-02-27T12:11:52","modified_gmt":"2024-02-27T11:11:52","slug":"il-tuo-progetto","status":"publish","type":"page","link":"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/","title":{"rendered":"Il tuo progetto"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; id=&#8221;beliefs&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#484847&#8243; text_color=&#8221;#333333&#8243; style=&#8221;regular_underline&#8221; highlight_expansion=&#8221;default&#8221; underline_thickness=&#8221;3px&#8221;]\n<h1><em>Il tuo progetto<\/em><\/h1>\n[\/nectar_highlighted_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1707207967186{margin-right: 5% !important;}&#8221;]Parliamo del vostro progetto in dettaglio! Se desideri fissare una consulenza, \u00e8 possibile contattarci per telefono, e-mail o tramite il modulo di contatto.<\/p>\n<p><strong>Non vediamo l&#8217;ora di conoscere il tuo progetto!<\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-12&#8243;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;0px&#8221; pointer_events=&#8221;all&#8221; url=&#8221;https:\/\/stephankofler.com\/it\/progetti\/schlosswirt\/&#8221; icon_fontawesome=&#8221;fa fa-angle-left&#8221;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;0px&#8221; pointer_events=&#8221;all&#8221; url=&#8221;https:\/\/stephankofler.com\/it\/progetti\/apfelhotel\/&#8221; icon_fontawesome=&#8221;fa fa-angle-right&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;1%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;1950&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;3&#8243; item_spacing=&#8221;6px&#8221; gallery_style=&#8221;5&#8243; load_in_animation=&#8221;none&#8221; img_size=&#8221;420&#215;420&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_global_section id=&#8221;3208&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_global_section id=&#8221;3214&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; id=&#8221;beliefs&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":3111,"menu_order":12,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3169","page","type-page","status-publish"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il tuo progetto - KOFLER STEPHAN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il tuo progetto - KOFLER STEPHAN\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; id=&#8221;beliefs&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/\" \/>\n<meta property=\"og:site_name\" content=\"KOFLER STEPHAN\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-27T11:11:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stephankofler.com\/wordpress\/wp-content\/uploads\/2024\/01\/Logo-Kofler-Stephan-Co-2x.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/\",\"url\":\"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/\",\"name\":\"Il tuo progetto - KOFLER STEPHAN\",\"isPartOf\":{\"@id\":\"https:\/\/stephankofler.com\/#website\"},\"datePublished\":\"2023-09-13T08:17:51+00:00\",\"dateModified\":\"2024-02-27T11:11:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/stephankofler.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROGETTI\",\"item\":\"https:\/\/stephankofler.com\/it\/progetti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il tuo progetto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stephankofler.com\/#website\",\"url\":\"https:\/\/stephankofler.com\/\",\"name\":\"KOFLER STEPHAN\",\"description\":\"MALERBETRIEB, TROCKENBAU, FASSADEN, D\u00c4MMUNGEN, TAPEZIEREN, DEKOR, PUTZ, FUGENLOS, LACKIERARBEITEN, AKUSTIKSYTEME, BESCHRIFTUNGEN\",\"publisher\":{\"@id\":\"https:\/\/stephankofler.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stephankofler.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stephankofler.com\/#organization\",\"name\":\"KOFLER STEPHAN\",\"url\":\"https:\/\/stephankofler.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/stephankofler.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stephankofler.com\/wordpress\/wp-content\/uploads\/2024\/01\/Logo-Kofler-Stephan-Co-2x.png\",\"contentUrl\":\"https:\/\/stephankofler.com\/wordpress\/wp-content\/uploads\/2024\/01\/Logo-Kofler-Stephan-Co-2x.png\",\"width\":800,\"height\":301,\"caption\":\"KOFLER STEPHAN\"},\"image\":{\"@id\":\"https:\/\/stephankofler.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/koflermalerbetrieb\/?hl=de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il tuo progetto - KOFLER STEPHAN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/","og_locale":"it_IT","og_type":"article","og_title":"Il tuo progetto - KOFLER STEPHAN","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; id=&#8221;beliefs&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/","og_site_name":"KOFLER STEPHAN","article_modified_time":"2024-02-27T11:11:52+00:00","og_image":[{"width":800,"height":301,"url":"https:\/\/stephankofler.com\/wordpress\/wp-content\/uploads\/2024\/01\/Logo-Kofler-Stephan-Co-2x.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/","url":"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/","name":"Il tuo progetto - KOFLER STEPHAN","isPartOf":{"@id":"https:\/\/stephankofler.com\/#website"},"datePublished":"2023-09-13T08:17:51+00:00","dateModified":"2024-02-27T11:11:52+00:00","breadcrumb":{"@id":"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stephankofler.com\/it\/progetti\/il-tuo-progetto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stephankofler.com\/it\/"},{"@type":"ListItem","position":2,"name":"PROGETTI","item":"https:\/\/stephankofler.com\/it\/progetti\/"},{"@type":"ListItem","position":3,"name":"Il tuo progetto"}]},{"@type":"WebSite","@id":"https:\/\/stephankofler.com\/#website","url":"https:\/\/stephankofler.com\/","name":"KOFLER STEPHAN","description":"MALERBETRIEB, TROCKENBAU, FASSADEN, D\u00c4MMUNGEN, TAPEZIEREN, DEKOR, PUTZ, FUGENLOS, LACKIERARBEITEN, AKUSTIKSYTEME, BESCHRIFTUNGEN","publisher":{"@id":"https:\/\/stephankofler.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stephankofler.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/stephankofler.com\/#organization","name":"KOFLER STEPHAN","url":"https:\/\/stephankofler.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/stephankofler.com\/#\/schema\/logo\/image\/","url":"https:\/\/stephankofler.com\/wordpress\/wp-content\/uploads\/2024\/01\/Logo-Kofler-Stephan-Co-2x.png","contentUrl":"https:\/\/stephankofler.com\/wordpress\/wp-content\/uploads\/2024\/01\/Logo-Kofler-Stephan-Co-2x.png","width":800,"height":301,"caption":"KOFLER STEPHAN"},"image":{"@id":"https:\/\/stephankofler.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/koflermalerbetrieb\/?hl=de"]}]}},"_links":{"self":[{"href":"https:\/\/stephankofler.com\/it\/wp-json\/wp\/v2\/pages\/3169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stephankofler.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stephankofler.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stephankofler.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stephankofler.com\/it\/wp-json\/wp\/v2\/comments?post=3169"}],"version-history":[{"count":0,"href":"https:\/\/stephankofler.com\/it\/wp-json\/wp\/v2\/pages\/3169\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stephankofler.com\/it\/wp-json\/wp\/v2\/pages\/3111"}],"wp:attachment":[{"href":"https:\/\/stephankofler.com\/it\/wp-json\/wp\/v2\/media?parent=3169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}